{"id":9230,"date":"2023-10-27T14:36:38","date_gmt":"2023-10-27T12:36:38","guid":{"rendered":"https:\/\/www.ease2pay.com\/?page_id=9230"},"modified":"2026-03-31T16:55:43","modified_gmt":"2026-03-31T14:55:43","slug":"wsa-rheine-schranke","status":"publish","type":"page","link":"https:\/\/www.ease2pay.com\/fr\/walstroom\/wsa-rheine-schranke\/","title":{"rendered":"WSA Rheine Schr\u00e4nke &#8211; Walstroom"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9230\" class=\"elementor elementor-9230\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5096f4 e-flex e-con-boxed e-con e-parent\" data-id=\"d5096f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:6183,&quot;url&quot;:&quot;https:\\\/\\\/www.ease2pay.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/katendrecht-vanaf-de.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-26a0c61 e-con-full e-flex e-con e-child\" data-id=\"26a0c61\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-432c896 e-con-full e-flex e-con e-child\" data-id=\"432c896\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-2b95cc9 e-con-full e-flex e-con e-child\" data-id=\"2b95cc9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7489ca3 elementor-align-right elementor-mobile-align-center elementor-tablet-align-center elementor-absolute elementor-hidden-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"7489ca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-wobble-vertical\" href=\"https:\/\/walstroom.eu\/mijnwalstroom\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">inloggen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df6c970 e-con-full e-flex e-con e-child\" data-id=\"df6c970\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-ccaee0c e-con-full e-flex e-con e-child\" data-id=\"ccaee0c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f3ff31 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"9f3ff31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/elementor\/thumbs\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png\" title=\"Icon_Walstroom_200px\" alt=\"Icon_Walstroom_200px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2bc2f6 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"e2bc2f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/elementor\/thumbs\/Icon_Walstroom_200px-qc0nji2uzyglmsqb7wvfcz1cqytvn8ayo7cdms3hmo.png\" title=\"Icon_Walstroom_200px\" alt=\"Icon_Walstroom_200px\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bac81f8 e-con-full e-flex e-con e-child\" data-id=\"bac81f8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f996894 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"f996894\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Walstroom<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af2119d elementor-widget elementor-widget-heading\" data-id=\"af2119d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie das funktioniert<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b18caab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b18caab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa7bb0a\" data-id=\"fa7bb0a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fca4cb1 elementor-widget elementor-widget-heading\" data-id=\"fca4cb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">So funktioniert Walstroom f\u00fcr WSA Rheine schr\u00e4nke<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c791f16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c791f16\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54fc7de6\" data-id=\"54fc7de6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66a9e37a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66a9e37a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e0ed38c\" data-id=\"2e0ed38c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a257450 elementor-widget elementor-widget-text-editor\" data-id=\"4a257450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Wichtige Sicherheitshinweise:<\/strong><\/p><p>a) Die Anlage darf nur von geschultem Personal bedient werden.<\/p><p>b) Die Verwendung von Kabeladaptern ist nicht gestattet.<\/p><p>c) Vor dem Einschalten: Stecker zuerst an Bord, dann an Land einstecken;<\/p><p>d) Nach dem Ausschalten: Zuerst an Land den Stecker ziehen, dann an Bord;<\/p><p>e) Verbinden Sie jedes Bordnetz mit nur einem Landstromanschluss.<\/p><p>f) Verwenden Sie nur Landstromkabel, die mit EN 15869-3 gekennzeichnet sind.<\/p><p>g) 400 V, 50 Hz; Maximal zul\u00e4ssiger Strom 16A, 32A, 63A, wie auf der Steckdose angegeben;<\/p><p>h) Die Steckdosen sind durch einen Fehlerstromschutzschalter (RCCB) von 30 mA (16A und 32A) oder 300 mA (63A) gesch\u00fctzt.<\/p><p>i) \u00dcberpr\u00fcfen Sie vor dem Gebrauch visuell die Stromanlage und die sichere Verlegung des Landstrom<\/p><p>j) Zul\u00e4ssige Kabell\u00e4nge 50 Meter.\u00ad\u00ad\u00ad Zul\u00e4ssiger Kabelquerschnitt 16A: 5&#215;2,5 mm<sup>2<\/sup>, 32A: 5&#215;4 mm<sup>2<\/sup>, 63 A: 5&#215;16 mm<sup>2<\/sup>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f83213c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f83213c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ec4d896\" data-id=\"7ec4d896\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13e9dffb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13e9dffb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-43a09552\" data-id=\"43a09552\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60f47d02 elementor-widget elementor-widget-text-editor\" data-id=\"60f47d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>1. VERWENDUNG<\/h2><p><strong>1.1 Anmeldung und Registrierung<\/strong><br \/>Der Landanschlusskasten kann erst in Gebrauch genommen werden, nachdem sich der Benutzer f\u00fcr den Walstroom registriert und angemeldet hat. Dies ist sowohl \u00fcber die Walstroom-App als auch \u00fcber die Website https:\/\/www.walstroom.eu m\u00f6glich. Die Stromlieferung kann auch \u00fcber die App oder den PC beendet werden. Die Walstroom-App ist f\u00fcr Android und Apple iOs verf\u00fcgbar.<\/p><p><strong>HINWEIS Benachrichtigung l\u00e4uft per SMS.<\/strong><br \/><strong>Vergessen Sie nicht, w\u00e4hrend Ihrer Registrierung Ihre Mobilfunknummer anzugeben!<\/strong><\/p><p><strong>1.1.1 Registrierung und Anmeldung \u00fcber die Walstroom-App<\/strong><br \/>1. Laden Sie sich die Walstroom-App herunter und installieren Sie diese.<\/p><p>2. Befolgen Sie die Schritte, die auf dem Display Ihres Smartphones angezeigt werden.<\/p><p>3. Nach Registrierung und Anmeldung wird die T\u00fcr des Kundenteils entriegelt.<\/p><p><strong>1.1.2 Registrierung und Anmeldung \u00fcber https:\/\/www.walstroom.eu<\/strong><br \/>1. \u00d6ffnen Sie die Internetseite https:\/\/www.walstroom.eu<\/p><p>2. Gehen Sie zu Sofort anmelden und befolgen Sie alle Schritte, die auf dem Display<br \/>angezeigt werden.<\/p><p>3. Nach Registrierung und Anmeldung wird die T\u00fcr des Kundenteils entriegelt<\/p><p><strong>1.2 Stromabnahme starten<\/strong><br \/>1. \u00d6ffnen Sie die T\u00fcr des Kundenteils \ud83c\udd71.<\/p><ul><li>Das Statusl\u00e4mpchen \u00fcber der T\u00fcr \ud83c\udd70 leuchtet gr\u00fcn.<\/li><li>Die Drucktaste Abbrechen \ud83c\udd72 blinkt rot.<\/li><li>Die Drucktasten bei den CEE-Steckdosen \ud83c\udd73 blinken gr\u00fcn.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c581f02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c581f02\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-199f8f0b\" data-id=\"199f8f0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d9c563a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9c563a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4022e451\" data-id=\"4022e451\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b751f6 elementor-widget elementor-widget-image\" data-id=\"5b751f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"400\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/duitsland_20201102.jpg\" class=\"attachment-large size-large wp-image-9232\" alt=\"\" srcset=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_20201102.jpg 1920w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_20201102-768x160.jpg 768w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_20201102-1536x320.jpg 1536w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_20201102-18x4.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c795db3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c795db3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59c5121\" data-id=\"59c5121\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-781a022 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"781a022\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-168b0d0\" data-id=\"168b0d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d06e2e3 elementor-widget elementor-widget-text-editor\" data-id=\"d06e2e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2. Stecken Sie den Stecker in die gew\u00fcnschte CEE-Steckdose: 16A, 32A, 63A (in der<br \/>Abbildung:\ud83c\udd74) und dr\u00fccken Sie die zugeh\u00f6rige Drucktaste F.<\/p><ul><li>Die Drucktaste Abbrechen \ud83c\udd78 erlischt.<\/li><li>Die Drucktaste der gew\u00e4hlten CEE-Steckdose (in der Abbildung:\ud83c\udd74) leuchtet<br \/>dauerhaft gr\u00fcn.<\/li><li>Die Drucktasten der sonstigen CEE-Steckdosen (in der Abbildung \ud83c\udd76 und \ud83c\udd77)<br \/>erl\u00f6schen.<\/li><\/ul><p>3. Wenn Sie die Transaktion abbrechen m\u00f6chten: Dr\u00fccken Sie auf die Drucktaste<br \/>Abbrechen \ud83c\udd78.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b827d80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b827d80\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55620c4\" data-id=\"55620c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a02ba90 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a02ba90\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7fab39a\" data-id=\"7fab39a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfa6ac5 elementor-widget elementor-widget-image\" data-id=\"cfa6ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"400\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/duitsland_2.jpg\" class=\"attachment-large size-large wp-image-9233\" alt=\"\" srcset=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_2.jpg 1920w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_2-768x160.jpg 768w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_2-1536x320.jpg 1536w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_2-18x4.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0287c7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0287c7c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ff32f3\" data-id=\"5ff32f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b758ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b758ac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c74c4f5\" data-id=\"c74c4f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c1fd79 elementor-widget elementor-widget-text-editor\" data-id=\"2c1fd79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>4. Schlie\u00dfen Sie die T\u00fcr \ud83c\udd79 .<\/p><p>5. Nach Schlie\u00dfen der T\u00fcr:<\/p><ul><li>steht das Stromkabel unter Spannung,<\/li><li>leuchtet das Statusl\u00e4mpchen \u00fcber der T\u00fcr \ud83c\udd7a dauerhaft blau.<\/li><\/ul><p><strong>Sobald die T\u00fcr des Kundenteils geschlossen wird, steht das Stromkabel, das an der<\/strong><br \/><strong>CEE-Steckdose angeschlossen ist, unter Spannung. <\/strong><\/p><p><strong>1.3 Stromabnahme stoppen<\/strong><\/p><p>\u00a0 1. Stoppen Sie die Stromabnahme:<\/p><ul><li>\u00fcber Ihren Account in der Walstroom-App<\/li><li>\u00fcber www.walstroom.eu<\/li><li>mit Ihrer RFID-Karte<\/li><\/ul><p>\u00a0 2. \u00d6ffnen Sie die T\u00fcr des Kundenteils.<\/p><p>\u00a0 3. Ziehen Sie die Stecker aus der CEE-Steckdose.<\/p><p>\u00a0 4. Zur Best\u00e4tigung der Beendigung der Stromzufuhr erhalten Sie eine SMS.<\/p><p>\u00a0 5. Schlie\u00dfen Sie die T\u00fcr. Das Statusl\u00e4mpchen \u00fcber der T\u00fcr leuchtet gr\u00fcn auf<\/p><p><strong>1.4 Statusleuchten<\/strong><\/p><p>Dieser Teil enth\u00e4lt eine komplette \u00dcbersicht der L\u00e4mpchen, die sich im<br \/>Landanschlusskasten und an der Au\u00dfenseite des Landanschlusskastens befinden.<strong>1.4.1 Statusleuchten Au\u00dfenseite<\/strong><\/p><p>\u00dcber der T\u00fcr des Kundenteils befindet sich das L\u00e4mpchen, das den Status des<br \/>WAK D63 anzeigt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18b2b00 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18b2b00\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f6e911\" data-id=\"9f6e911\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8831642 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8831642\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e8c5bb9\" data-id=\"e8c5bb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25d7563 elementor-widget elementor-widget-image\" data-id=\"25d7563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"400\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/duitsland_3.jpg\" class=\"attachment-large size-large wp-image-9234\" alt=\"\" srcset=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_3.jpg 1920w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_3-768x160.jpg 768w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_3-1536x320.jpg 1536w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/duitsland_3-18x4.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e9fe85 elementor-widget elementor-widget-image\" data-id=\"3e9fe85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"400\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/lampjes1.jpg\" class=\"attachment-large size-large wp-image-9235\" alt=\"\" srcset=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes1.jpg 1920w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes1-768x160.jpg 768w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes1-1536x320.jpg 1536w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes1-18x4.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad74981 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad74981\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6903ecf\" data-id=\"6903ecf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a41a57e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a41a57e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b66f583\" data-id=\"b66f583\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b85feb6 elementor-widget elementor-widget-text-editor\" data-id=\"b85feb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1.4.2 Statusleuchten Innenseite<\/strong><\/p><p>Jeder CEE-Stecker besitzt eine eigene Drucktaste. Sobald sich die T\u00fcr des Kundenteils<br \/>\u00f6ffnet, blinken die Drucktasten gr\u00fcn. Sobald der Benutzer seine Wahl getroffen hat (indem<br \/>er auf eine der Drucktasten gedr\u00fcckt hat), leuchtet die betreffende Drucktaste dauerhaft<br \/>gr\u00fcn. Die anderen Drucktasten erl\u00f6schen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4025b765 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4025b765\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e6aeeeb\" data-id=\"1e6aeeeb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-26742fe2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26742fe2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5e1b564\" data-id=\"5e1b564\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f7703a elementor-widget elementor-widget-menu-anchor\" data-id=\"7f7703a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"download-walstroom\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3471346 elementor-widget elementor-widget-image\" data-id=\"3471346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"400\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/stekkers.jpg\" class=\"attachment-large size-large wp-image-9236\" alt=\"\" srcset=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/stekkers.jpg 1920w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/stekkers-768x160.jpg 768w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/stekkers-1536x320.jpg 1536w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/stekkers-18x4.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9626e67 elementor-widget elementor-widget-image\" data-id=\"9626e67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"400\" src=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/lampjes2.jpg\" class=\"attachment-large size-large wp-image-9237\" alt=\"\" srcset=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes2.jpg 1920w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes2-768x160.jpg 768w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes2-1536x320.jpg 1536w, https:\/\/www.ease2pay.com\/wp-content\/uploads\/\/lampjes2-18x4.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-314c7a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"314c7a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-246a1c8\" data-id=\"246a1c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af27c08 elementor-widget elementor-widget-heading\" data-id=\"af27c08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaad4f9 elementor-widget elementor-widget-accordion\" data-id=\"eaad4f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2461\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2461\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ich kann die T\u00fcr des Kastens nicht \u00f6ffnen.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2461\"><p>Kontrollieren Sie, ob Sie versucht haben, die richtige T\u00fcr zu<br \/>\u00f6ffnen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2462\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2462\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Die T\u00fcr des Kastens \u00f6ffnet sich, aber es leuchtet kein einziges L\u00e4mpchen.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2462\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2462\"><p>Die Stromzufuhr wurde \u00fcber die Walstroom-App, www.walstroom.eu oder die RFID-Karte beendet.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2463\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2463\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Die T\u00fcr des Kastens \u00f6ffnet sich, und die Taste \u201e Abbrechenblinkt rot.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2463\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2463\"><p>Dr\u00fccken Sie auf die Taste der Steckdose, die Sie nutzen m\u00f6chten, oder dr\u00fccken Sie auf die Taste \u201eAbbrechen, um die Stromzufuhr abzubrechen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2464\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2464\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ich halte meine RFID-Karte vor den Sensor, aber die T\u00fcr \u00f6ffnet sich nicht.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2464\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2464\"><p>Kontrollieren Sie das Statusl\u00e4mpchen \u00fcber der T\u00fcr des Kundenteils. Wenn das L\u00e4mpchen gr\u00fcn blinkt oder dauerhaft leuchtet, ist Ihre Karte m\u00f6glicherweise defekt oder gesperrt.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2465\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2465\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ich wei\u00df nicht genau, ob der Z\u00e4hlerstand zu Beginn korrekt ist<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2465\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2465\"><p>Sehen Sie durch das Fenster der T\u00fcr des Serviceteils und notieren Sie sich den Stand des kWh-Z\u00e4hlers. Nach Beendigung der Stromabnahme k\u00f6nnen Sie \u00fcber den Public<br \/>Key kontrollieren, ob Ihr Stromverbrauch korrekt an walstrom.eu \u00fcbertragen wurde. Das Messsystem wurde im Einklang mit dem geltenden Eichrecht getestet und zertifiziert<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2466\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2466\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Woher wei\u00df ich, ob der angegebene Z\u00e4hlerstand korrekt ist?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2466\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2466\"><p>Notieren Sie sich den kWh-Z\u00e4hlerstand vor Beginn der Stromzufuhr und nach Beendigung der Stromzufuhr. Nach Beendigung der Stromzufuhr k\u00f6nnen Sie \u00fcber den Public Key kontrollieren, ob Ihr Stromverbrauch korrekt an walstrom.eu \u00fcbertragen wurde. Die Daten\u00fcbertragung erfolgt verschl\u00fcsselt und ist f\u00fcr jeden Benutzer einsehbar.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2467\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2467\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Welchen Zweck hat der Public Key?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2467\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2467\"><p>Die Public Key-Verschl\u00fcsselung ist eine Methode zur Sicherung digitaler Daten. Der Absender der Informationen (in diesem Fall der Stromabnehmer) ruft den Public Key ab und verschl\u00fcsselt damit die Verbrauchsdaten, so dass diese auf sichere Weise versendet werden k\u00f6nnen. Der Empf\u00e4nger nutzt anschlie\u00dfend seinen Private Key, um diese Informationen zu entschl\u00fcsseln.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2468\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2468\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ich habe kein Smartphone. Wie kann ich mir die Daten des Public Key ansehen?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2468\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2468\"><p>\u00d6ffnen Sie die Internetseite www.walstroom.eu\/de und laden Sie sich die Transparenz-Software herunter. Um sich die Daten des Public Key ansehen zu k\u00f6nnen, befolgen Sie einfach die Anweisungen in der Software.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2469\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2469\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ich habe kein Internet.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2469\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2469\"><p>In diesem Fall k\u00f6nnen Sie den Landanschlusskasten nur mit der RFID-Karte bedienen. Diese k\u00f6nnen Sie telefonisch unter der Nummer bestellen, die auf dem Landanschlusskasten angegeben ist.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24610\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-24610\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ich wei\u00df nicht, welche Stromst\u00e4rke ich w\u00e4hlen muss.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-24610\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-24610\"><div id=\"ui-id-20\" class=\"ui-accordion-content ui-corner-bottom ui-helper-reset ui-widget-content ui-accordion-content-active\" role=\"tabpanel\" aria-labelledby=\"ui-id-19\" aria-hidden=\"false\"><p>H\u00e4ufig liefert die Farbe Ihres Steckers einen Anhaltspunkt. Blaue Stecker sind 230V 1Phase 16A. Die roten Stecker k\u00f6nnen variieren und sind 16A, 32A oder 63A. Allerdings variieren die Ma\u00dfe der Stecker, ein Stecker kann also nie an der falschen<br \/>Steckdose angeschlossen werden.<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-24611\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-24611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Im Landanschlusskasten liegt eine St\u00f6rung vor.<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-24611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-24611\"><p>Melden Sie die St\u00f6rung unter der Telefonnummer, die auf dem Landanschlusskasten angegeben ist.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ed8cfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ed8cfc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45fa6b4\" data-id=\"45fa6b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24c001f elementor-widget elementor-widget-heading\" data-id=\"24c001f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/apps-diensten\/walstroom\/\">Zur\u00fcck zur Startseite von  Walstroom<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>inloggen Walstroom Wie das funktioniert So funktioniert Walstroom f\u00fcr WSA Rheine schr\u00e4nke Wichtige Sicherheitshinweise: a) Die Anlage darf nur von geschultem Personal bedient werden. b) Die Verwendung von Kabeladaptern ist nicht gestattet. c) Vor dem Einschalten: Stecker zuerst an Bord, dann an Land einstecken; d) Nach dem Ausschalten: Zuerst an Land den Stecker ziehen, dann [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":6331,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-9230","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>WSA Rheine Schr\u00e4nke - Walstroom - Ease2pay Hoe werkt Ease2pay Walstroom<\/title>\n<meta name=\"description\" content=\"Meld je gratis aan als gebruiker op deze website of via de Ease2pay Walstroom app. Hierna kan je door heel Europa gebruikmaken van onze diensten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ease2pay.com\/fr\/walstroom\/wsa-rheine-schranke\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WSA Rheine Schr\u00e4nke - Walstroom\" \/>\n<meta property=\"og:description\" content=\"Meld je gratis aan als gebruiker op deze website of via de Ease2pay Walstroom app. Hierna kan je door heel Europa gebruikmaken van onze diensten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ease2pay.com\/fr\/walstroom\/wsa-rheine-schranke\/\" \/>\n<meta property=\"og:site_name\" content=\"Ease2pay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ease2pay\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T14:55:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ease2pay.com\/wp-content\/uploads\/elementor\/thumbs\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Ease2pay\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/\",\"url\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/\",\"name\":\"WSA Rheine Schr\u00e4nke - Walstroom - Ease2pay Hoe werkt Ease2pay Walstroom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ease2pay.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png\",\"datePublished\":\"2023-10-27T12:36:38+00:00\",\"dateModified\":\"2026-03-31T14:55:43+00:00\",\"description\":\"Meld je gratis aan als gebruiker op deze website of via de Ease2pay Walstroom app. Hierna kan je door heel Europa gebruikmaken van onze diensten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ease2pay.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png\",\"contentUrl\":\"https:\\\/\\\/www.ease2pay.com\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ease2pay.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walstroom\",\"item\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WSA Rheine Schr\u00e4nke &#8211; Walstroom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/#website\",\"url\":\"https:\\\/\\\/www.ease2pay.com\\\/\",\"name\":\"Ease2pay.com\",\"description\":\"Self service for energy, transport and more\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ease2pay.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/#organization\",\"name\":\"Ease2pay\",\"url\":\"https:\\\/\\\/www.ease2pay.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ease2pay\",\"https:\\\/\\\/x.com\\\/Ease2pay\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/18239877\\\/admin\\\/dashboard\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ease2paynl\\\/\"],\"description\":\"Ontdek het gemak van selfservice. Reserveer, activeer en betaal jouw stroom, water en verblijf op diverse locaties. Regel alles met \u00e9\u00e9n druk op de knop.\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ease2pay.com\\\/walstroom\\\/wsa-rheine-schranke\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.ease2pay.com\\\/wp-content\\\/uploads\\\/Ease2pay-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ease2pay.com\\\/wp-content\\\/uploads\\\/Ease2pay-logo.png\",\"width\":500,\"height\":86,\"caption\":\"Ease2pay\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WSA Rheine Schr\u00e4nke - Walstroom - Ease2pay Hoe werkt Ease2pay Walstroom","description":"Meld je gratis aan als gebruiker op deze website of via de Ease2pay Walstroom app. Hierna kan je door heel Europa gebruikmaken van onze diensten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ease2pay.com\/fr\/walstroom\/wsa-rheine-schranke\/","og_locale":"fr_FR","og_type":"article","og_title":"WSA Rheine Schr\u00e4nke - Walstroom","og_description":"Meld je gratis aan als gebruiker op deze website of via de Ease2pay Walstroom app. Hierna kan je door heel Europa gebruikmaken van onze diensten.","og_url":"https:\/\/www.ease2pay.com\/fr\/walstroom\/wsa-rheine-schranke\/","og_site_name":"Ease2pay","article_publisher":"https:\/\/www.facebook.com\/ease2pay","article_modified_time":"2026-03-31T14:55:43+00:00","og_image":[{"url":"https:\/\/www.ease2pay.com\/wp-content\/uploads\/elementor\/thumbs\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Ease2pay","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/","url":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/","name":"WSA Rheine Schr\u00e4nke - Walstroom - Ease2pay Hoe werkt Ease2pay Walstroom","isPartOf":{"@id":"https:\/\/www.ease2pay.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#primaryimage"},"image":{"@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ease2pay.com\/wp-content\/uploads\/elementor\/thumbs\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png","datePublished":"2023-10-27T12:36:38+00:00","dateModified":"2026-03-31T14:55:43+00:00","description":"Meld je gratis aan als gebruiker op deze website of via de Ease2pay Walstroom app. Hierna kan je door heel Europa gebruikmaken van onze diensten.","breadcrumb":{"@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#primaryimage","url":"https:\/\/www.ease2pay.com\/wp-content\/uploads\/elementor\/thumbs\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png","contentUrl":"https:\/\/www.ease2pay.com\/wp-content\/uploads\/elementor\/thumbs\/Icon_Walstroom_200px-qc0nji2uzygvv3egdy7nmiycxw1za6ajyy3an9cyrk.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ease2pay.com\/"},{"@type":"ListItem","position":2,"name":"Walstroom","item":"https:\/\/www.ease2pay.com\/walstroom\/"},{"@type":"ListItem","position":3,"name":"WSA Rheine Schr\u00e4nke &#8211; Walstroom"}]},{"@type":"WebSite","@id":"https:\/\/www.ease2pay.com\/#website","url":"https:\/\/www.ease2pay.com\/","name":"Ease2pay.com","description":"Self service for energy, transport and more","publisher":{"@id":"https:\/\/www.ease2pay.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ease2pay.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.ease2pay.com\/#organization","name":"Ease2pay","url":"https:\/\/www.ease2pay.com\/","logo":{"@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/ease2pay","https:\/\/x.com\/Ease2pay","https:\/\/www.linkedin.com\/company\/18239877\/admin\/dashboard\/","https:\/\/www.instagram.com\/ease2paynl\/"],"description":"D\u00e9couvrez la commodit\u00e9 du libre-service. R\u00e9servez, activez et payez votre \u00e9lectricit\u00e9, votre eau et votre logement \u00e0 diff\u00e9rents endroits. Il vous suffit d'appuyer sur un bouton pour tout organiser.","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ease2pay.com\/walstroom\/wsa-rheine-schranke\/#local-main-organization-logo","url":"https:\/\/www.ease2pay.com\/wp-content\/uploads\/Ease2pay-logo.png","contentUrl":"https:\/\/www.ease2pay.com\/wp-content\/uploads\/Ease2pay-logo.png","width":500,"height":86,"caption":"Ease2pay"}]}},"_links":{"self":[{"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/pages\/9230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/comments?post=9230"}],"version-history":[{"count":0,"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/pages\/9230\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/pages\/6331"}],"wp:attachment":[{"href":"https:\/\/www.ease2pay.com\/fr\/wp-json\/wp\/v2\/media?parent=9230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}